{"id":19994,"date":"2025-02-13T23:55:09","date_gmt":"2025-02-14T02:55:09","guid":{"rendered":"https:\/\/www.portaldenoticias.net\/ffsantos\/?p=19994"},"modified":"2025-02-15T10:48:43","modified_gmt":"2025-02-15T13:48:43","slug":"humana-seguros-e-seus-34-anos","status":"publish","type":"post","link":"https:\/\/portaldenoticias.net\/ffsantos\/humana-seguros-e-seus-34-anos\/","title":{"rendered":"HUMANA SEGUROS E SEUS 34 ANOS"},"content":{"rendered":"<p style=\"text-align: center\"><strong><em><a href=\"https:\/\/www.portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2025\/02\/Logo-Humana_1024x227.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-19995\" src=\"https:\/\/www.portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2025\/02\/Logo-Humana_1024x227.png\" alt=\"\" width=\"1024\" height=\"227\" srcset=\"https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2025\/02\/Logo-Humana_1024x227.png 1024w, https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2025\/02\/Logo-Humana_1024x227-300x67.png 300w, https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2025\/02\/Logo-Humana_1024x227-768x170.png 768w, https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2025\/02\/Logo-Humana_1024x227-150x33.png 150w, https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2025\/02\/Logo-Humana_1024x227-450x100.png 450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a>Mais do que crescer, Humana Seguros quer gerar oportunidades<\/em><\/strong><\/p>\n<p style=\"text-align: center\"><strong><em>Assessoria comandada por Rodrigo Bertacini chega aos 34 anos com bom desempenho, novas parcerias, investimentos e prop\u00f3sitos que v\u00e3o al\u00e9m do crescimento.<\/em><\/strong><\/p>\n<figure id=\"attachment_19996\" aria-describedby=\"caption-attachment-19996\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2025\/02\/Bertacini-2-Rodrigo-Bertacini_horiz1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-19996\" src=\"https:\/\/www.portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2025\/02\/Bertacini-2-Rodrigo-Bertacini_horiz1-300x271.jpg\" alt=\"\" width=\"300\" height=\"271\" srcset=\"https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2025\/02\/Bertacini-2-Rodrigo-Bertacini_horiz1-300x271.jpg 300w, https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2025\/02\/Bertacini-2-Rodrigo-Bertacini_horiz1-1024x926.jpg 1024w, https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2025\/02\/Bertacini-2-Rodrigo-Bertacini_horiz1-768x695.jpg 768w, https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2025\/02\/Bertacini-2-Rodrigo-Bertacini_horiz1-150x136.jpg 150w, https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2025\/02\/Bertacini-2-Rodrigo-Bertacini_horiz1-450x407.jpg 450w, https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2025\/02\/Bertacini-2-Rodrigo-Bertacini_horiz1-1200x1086.jpg 1200w, https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2025\/02\/Bertacini-2-Rodrigo-Bertacini_horiz1.jpg 1269w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-19996\" class=\"wp-caption-text\">Rodrigo Bertacini<\/figcaption><\/figure>\n<p>Fundada no dia 2 de janeiro de 1991 pelo saudoso Osmar Bertacini, ex-presidente do CVG-SP, a Humana Seguros, uma das mais importantes assessorias de seguros do mercado, chega aos 34 anos de exist\u00eancia com bom desempenho, foco na melhoria cont\u00ednua dos servi\u00e7os e prop\u00f3sitos que v\u00e3o al\u00e9m do crescimento.<\/p>\n<p><strong><em>\u201cAcredito muito que crescer por crescer n\u00e3o \u00e9 o caminho ideal. O maior desafio \u00e9 gerar oportunidades\u201d<\/em><\/strong>, diz Rodrigo Bertacini, que est\u00e1 no comando da empresa desde 2019.<\/p>\n<p>Bertacini explica que a Humana deseja gerar oportunidades de carreiras, de novas posi\u00e7\u00f5es de trabalho e tamb\u00e9m colaborar para um mercado menos agressivo e mais compreensivo. Todos esses prop\u00f3sitos se alinham ao legado do fundador. <strong><em>\u201cEu e todos os nossos colaboradores, continuaremos a trilhar essa trajet\u00f3ria magn\u00edfica iniciada por meu querido pai, entregando o nosso melhor para atender as necessidades de nossa rede &#8211; clientes corretores, seguradores e, de forma indireta, segurados -, os mais importantes integrantes do mercado\u201d<\/em><\/strong>, diz.<\/p>\n<p style=\"text-align: center\"><strong><em>Ano de crescimento<\/em><\/strong><\/p>\n<p>Em um retrospecto de 2024, Bertacini reconhece que foi um ano de muitos desafios. <strong><em>\u201cHouve muitas mudan\u00e7as de mercado e de regula\u00e7\u00e3o, disputas acirradas por pre\u00e7o e rentabilidade (especialmente no auto e no sa\u00fade), complexidades inerentes \u00e0 condi\u00e7\u00e3o de estabilidade econ\u00f4mica do pa\u00eds, al\u00e9m de incertezas com a reforma tribut\u00e1ria\u201d<\/em><\/strong>, diz. Mesmo assim, a Humana registrou bom desempenho. <strong><em>\u201cCrescemos tanto em n\u00famero de corretores afiliados como em pr\u00eamios emitidos, fortalecendo nossa rela\u00e7\u00e3o com corretores e seguradoras\u201d<\/em><\/strong>, diz.<\/p>\n<p>Para promover o progresso da Humana, Bertacini aplicou internamente as bases da filosofia MAIS+, que estabelece um protocolo para as rela\u00e7\u00f5es profissionais e uma forma padronizada de agir. Todas as a\u00e7\u00f5es, segundo ele, devem ter em seu cerne quatro elementos que norteiam o comportamento profissional. Na pr\u00e1tica, todos devem ter Motiva\u00e7\u00e3o, serem Atenciosos, Inclusivos e Simples. <strong><em>\u201cEstes elementos passaram a ser o nosso mantra di\u00e1rio. O resultado deste trabalho \u00e9 vis\u00edvel em nossos n\u00fameros crescentes\u201d<\/em><\/strong>, diz.<\/p>\n<p>Outro importante investimento da Humana foi em tecnologia, come\u00e7ando pelo chatbot para facilitar e otimizar o processo de atendimento. Al\u00e9m de substituir equipamentos e computadores, a empresa implantou, ainda, o sistema de an\u00e1lise de neg\u00f3cios Power BI, que transforma dados em informa\u00e7\u00f5es e possibilita a administra\u00e7\u00e3o e o controle do volume de neg\u00f3cios da empresa. Para intensificar sua presen\u00e7a nas redes sociais, a Humana conta uma assessoria de marketing digital.<\/p>\n<p>No ano passado, a Humana avan\u00e7ou em parcerias, firmando neg\u00f3cios importantes. Um deles foi com a OMINT, que refor\u00e7ou o portf\u00f3lio de benef\u00edcios, e o outro com a EZZE, companhia que tem apresentado bons resultados. Bertacini revela que nos \u00faltimos anos a empresa tem recebido in\u00fameras propostas de parcerias, que s\u00e3o analisadas cuidadosamente. Dentre os crit\u00e9rios de escolha est\u00e3o a oferta servi\u00e7os de qualidade aos clientes corretores e, ainda, a possibilidade de bons resultados aos parceiros de neg\u00f3cios.<\/p>\n<p><strong><em>Trabalho humanizado<\/em><\/strong><\/p>\n<figure id=\"attachment_19997\" aria-describedby=\"caption-attachment-19997\" style=\"width: 297px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2025\/02\/Bertacini-Imagem1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-19997\" src=\"https:\/\/www.portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2025\/02\/Bertacini-Imagem1-297x300.png\" alt=\"\" width=\"297\" height=\"300\" srcset=\"https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2025\/02\/Bertacini-Imagem1-297x300.png 297w, https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2025\/02\/Bertacini-Imagem1-150x152.png 150w, https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2025\/02\/Bertacini-Imagem1-450x455.png 450w, https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2025\/02\/Bertacini-Imagem1.png 497w\" sizes=\"auto, (max-width: 297px) 100vw, 297px\" \/><\/a><figcaption id=\"caption-attachment-19997\" class=\"wp-caption-text\">Rodrigo Bertacini<\/figcaption><\/figure>\n<p>Como empresa do segmento de assessorias, a Humana, na vis\u00e3o de Bertacini, compartilha com seguradoras e corretores a responsabilidade de levar a mensagem do seguro para a popula\u00e7\u00e3o.<\/p>\n<p>Ele avalia que o mercado est\u00e1 em franco desenvolvimento e matura\u00e7\u00e3o, mas tem pela frente o desafio de desmistificar o seguro. <strong><em>\u201cNa percep\u00e7\u00e3o da popula\u00e7\u00e3o, o seguro est\u00e1 relacionado a fatos desagrad\u00e1veis, a come\u00e7ar pelo nome que se d\u00e1 \u00e0 ocorr\u00eancia, sinistro. O desafio \u00e9 mostrar que seguro \u00e9 prote\u00e7\u00e3o, cuidado, carinho e responsabilidade social\u201d<\/em><\/strong>, diz.<\/p>\n<p>Considerando o cen\u00e1rio de mortalidade precoce das empresas brasileiras, em que quase 35% encerram suas atividades nos dois primeiros anos, a Humana tem se mostrado um neg\u00f3cio perene. <strong><em>\u201cAlguma coisa estamos fazendo certo\u201d<\/em><\/strong>, brinca Bertacini, cuja meta para a empresa \u00e9 continuar crescendo de forma sustent\u00e1vel, org\u00e2nica e respons\u00e1vel. <strong><em>\u201cAcredito que a honestidade com nossos parceiros, a confian\u00e7a de que faremos o melhor e, acima de tudo, fazendo um trocadilho, nosso trabalho humanizado, nos trouxe at\u00e9 aqui e nos levar\u00e1 adiante por muitos e muitos anos ainda\u201d<\/em><\/strong>, diz.<\/p>\n<p><strong><em><a href=\"https:\/\/www.portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2021\/04\/Marcia-Alves.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-13741\" src=\"https:\/\/www.portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2021\/04\/Marcia-Alves.jpg\" alt=\"\" width=\"90\" height=\"90\" \/><\/a>Fonte:<\/em><\/strong> CVG-SP &#8211;<strong><em>Texto:<\/em><\/strong> M\u00e1rcia Alves &#8211; <a href=\"https:\/\/cvg.org.br\">https:\/\/cvg.org.br<\/a> &#8211; \u00a0<a href=\"https:\/\/www.humanaseguros.com.br\/\">https:\/\/www.humanaseguros.com.br\/<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><strong><em>Blog do Florisvaldo &#8211; Informa\u00e7\u00e3o com Imparcialidade<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mais do que crescer, Humana Seguros quer gerar oportunidades Assessoria comandada por Rodrigo Bertacini chega aos 34 anos com bom desempenho, novas parcerias, investimentos e prop\u00f3sitos que v\u00e3o al\u00e9m do crescimento. Fundada no dia 2 de janeiro de 1991 pelo saudoso Osmar Bertacini, ex-presidente do CVG-SP, a Humana Seguros, uma das mais importantes assessorias de<\/p>\n","protected":false},"author":2,"featured_media":19996,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,1,6],"tags":[],"class_list":{"0":"post-19994","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-destaques","9":"category-economia"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HUMANA SEGUROS E SEUS 34 ANOS - Blog do Florisvaldo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/portaldenoticias.net\/ffsantos\/humana-seguros-e-seus-34-anos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HUMANA SEGUROS E SEUS 34 ANOS - Blog do Florisvaldo\" \/>\n<meta property=\"og:description\" content=\"Mais do que crescer, Humana Seguros quer gerar oportunidades Assessoria comandada por Rodrigo Bertacini chega aos 34 anos com bom desempenho, novas parcerias, investimentos e prop\u00f3sitos que v\u00e3o al\u00e9m do crescimento. Fundada no dia 2 de janeiro de 1991 pelo saudoso Osmar Bertacini, ex-presidente do CVG-SP, a Humana Seguros, uma das mais importantes assessorias de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/portaldenoticias.net\/ffsantos\/humana-seguros-e-seus-34-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Florisvaldo\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-14T02:55:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-15T13:48:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2025\/02\/Bertacini-2-Rodrigo-Bertacini_horiz1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1269\" \/>\n\t<meta property=\"og:image:height\" content=\"1148\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Florisvaldo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Florisvaldo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/humana-seguros-e-seus-34-anos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/humana-seguros-e-seus-34-anos\\\/\"},\"author\":{\"name\":\"Florisvaldo\",\"@id\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/#\\\/schema\\\/person\\\/709c788ecb22f2378d698c2cd46cecc3\"},\"headline\":\"HUMANA SEGUROS E SEUS 34 ANOS\",\"datePublished\":\"2025-02-14T02:55:09+00:00\",\"dateModified\":\"2025-02-15T13:48:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/humana-seguros-e-seus-34-anos\\\/\"},\"wordCount\":770,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/humana-seguros-e-seus-34-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Bertacini-2-Rodrigo-Bertacini_horiz1.jpg\",\"articleSection\":[\"Brasil\",\"Destaques\",\"Economia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/humana-seguros-e-seus-34-anos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/humana-seguros-e-seus-34-anos\\\/\",\"url\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/humana-seguros-e-seus-34-anos\\\/\",\"name\":\"HUMANA SEGUROS E SEUS 34 ANOS - Blog do Florisvaldo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/humana-seguros-e-seus-34-anos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/humana-seguros-e-seus-34-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Bertacini-2-Rodrigo-Bertacini_horiz1.jpg\",\"datePublished\":\"2025-02-14T02:55:09+00:00\",\"dateModified\":\"2025-02-15T13:48:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/#\\\/schema\\\/person\\\/709c788ecb22f2378d698c2cd46cecc3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/humana-seguros-e-seus-34-anos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/humana-seguros-e-seus-34-anos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/humana-seguros-e-seus-34-anos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Bertacini-2-Rodrigo-Bertacini_horiz1.jpg\",\"contentUrl\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Bertacini-2-Rodrigo-Bertacini_horiz1.jpg\",\"width\":1269,\"height\":1148,\"caption\":\"Rodrigo Bertacini\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/humana-seguros-e-seus-34-anos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HUMANA SEGUROS E SEUS 34 ANOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/#website\",\"url\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/\",\"name\":\"Blog do Florisvaldo |\",\"description\":\"Informa\u00e7\u00e3o com imparcialidade\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/#\\\/schema\\\/person\\\/709c788ecb22f2378d698c2cd46cecc3\",\"name\":\"Florisvaldo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23c59839b4c874bb227d4916d18ba065e405a73d0e423fa9255ba9436604e628?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23c59839b4c874bb227d4916d18ba065e405a73d0e423fa9255ba9436604e628?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23c59839b4c874bb227d4916d18ba065e405a73d0e423fa9255ba9436604e628?s=96&d=mm&r=g\",\"caption\":\"Florisvaldo\"},\"url\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/author\\\/ffsantos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HUMANA SEGUROS E SEUS 34 ANOS - Blog do Florisvaldo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/portaldenoticias.net\/ffsantos\/humana-seguros-e-seus-34-anos\/","og_locale":"pt_BR","og_type":"article","og_title":"HUMANA SEGUROS E SEUS 34 ANOS - Blog do Florisvaldo","og_description":"Mais do que crescer, Humana Seguros quer gerar oportunidades Assessoria comandada por Rodrigo Bertacini chega aos 34 anos com bom desempenho, novas parcerias, investimentos e prop\u00f3sitos que v\u00e3o al\u00e9m do crescimento. Fundada no dia 2 de janeiro de 1991 pelo saudoso Osmar Bertacini, ex-presidente do CVG-SP, a Humana Seguros, uma das mais importantes assessorias de","og_url":"https:\/\/portaldenoticias.net\/ffsantos\/humana-seguros-e-seus-34-anos\/","og_site_name":"Blog do Florisvaldo","article_published_time":"2025-02-14T02:55:09+00:00","article_modified_time":"2025-02-15T13:48:43+00:00","og_image":[{"width":1269,"height":1148,"url":"https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2025\/02\/Bertacini-2-Rodrigo-Bertacini_horiz1.jpg","type":"image\/jpeg"}],"author":"Florisvaldo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Florisvaldo","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/portaldenoticias.net\/ffsantos\/humana-seguros-e-seus-34-anos\/#article","isPartOf":{"@id":"https:\/\/portaldenoticias.net\/ffsantos\/humana-seguros-e-seus-34-anos\/"},"author":{"name":"Florisvaldo","@id":"https:\/\/portaldenoticias.net\/ffsantos\/#\/schema\/person\/709c788ecb22f2378d698c2cd46cecc3"},"headline":"HUMANA SEGUROS E SEUS 34 ANOS","datePublished":"2025-02-14T02:55:09+00:00","dateModified":"2025-02-15T13:48:43+00:00","mainEntityOfPage":{"@id":"https:\/\/portaldenoticias.net\/ffsantos\/humana-seguros-e-seus-34-anos\/"},"wordCount":770,"commentCount":0,"image":{"@id":"https:\/\/portaldenoticias.net\/ffsantos\/humana-seguros-e-seus-34-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2025\/02\/Bertacini-2-Rodrigo-Bertacini_horiz1.jpg","articleSection":["Brasil","Destaques","Economia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/portaldenoticias.net\/ffsantos\/humana-seguros-e-seus-34-anos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/portaldenoticias.net\/ffsantos\/humana-seguros-e-seus-34-anos\/","url":"https:\/\/portaldenoticias.net\/ffsantos\/humana-seguros-e-seus-34-anos\/","name":"HUMANA SEGUROS E SEUS 34 ANOS - Blog do Florisvaldo","isPartOf":{"@id":"https:\/\/portaldenoticias.net\/ffsantos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/portaldenoticias.net\/ffsantos\/humana-seguros-e-seus-34-anos\/#primaryimage"},"image":{"@id":"https:\/\/portaldenoticias.net\/ffsantos\/humana-seguros-e-seus-34-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2025\/02\/Bertacini-2-Rodrigo-Bertacini_horiz1.jpg","datePublished":"2025-02-14T02:55:09+00:00","dateModified":"2025-02-15T13:48:43+00:00","author":{"@id":"https:\/\/portaldenoticias.net\/ffsantos\/#\/schema\/person\/709c788ecb22f2378d698c2cd46cecc3"},"breadcrumb":{"@id":"https:\/\/portaldenoticias.net\/ffsantos\/humana-seguros-e-seus-34-anos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/portaldenoticias.net\/ffsantos\/humana-seguros-e-seus-34-anos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/portaldenoticias.net\/ffsantos\/humana-seguros-e-seus-34-anos\/#primaryimage","url":"https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2025\/02\/Bertacini-2-Rodrigo-Bertacini_horiz1.jpg","contentUrl":"https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2025\/02\/Bertacini-2-Rodrigo-Bertacini_horiz1.jpg","width":1269,"height":1148,"caption":"Rodrigo Bertacini"},{"@type":"BreadcrumbList","@id":"https:\/\/portaldenoticias.net\/ffsantos\/humana-seguros-e-seus-34-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/portaldenoticias.net\/ffsantos\/"},{"@type":"ListItem","position":2,"name":"HUMANA SEGUROS E SEUS 34 ANOS"}]},{"@type":"WebSite","@id":"https:\/\/portaldenoticias.net\/ffsantos\/#website","url":"https:\/\/portaldenoticias.net\/ffsantos\/","name":"Blog do Florisvaldo |","description":"Informa\u00e7\u00e3o com imparcialidade","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/portaldenoticias.net\/ffsantos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/portaldenoticias.net\/ffsantos\/#\/schema\/person\/709c788ecb22f2378d698c2cd46cecc3","name":"Florisvaldo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/23c59839b4c874bb227d4916d18ba065e405a73d0e423fa9255ba9436604e628?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/23c59839b4c874bb227d4916d18ba065e405a73d0e423fa9255ba9436604e628?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/23c59839b4c874bb227d4916d18ba065e405a73d0e423fa9255ba9436604e628?s=96&d=mm&r=g","caption":"Florisvaldo"},"url":"https:\/\/portaldenoticias.net\/ffsantos\/author\/ffsantos\/"}]}},"_links":{"self":[{"href":"https:\/\/portaldenoticias.net\/ffsantos\/wp-json\/wp\/v2\/posts\/19994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portaldenoticias.net\/ffsantos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaldenoticias.net\/ffsantos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaldenoticias.net\/ffsantos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaldenoticias.net\/ffsantos\/wp-json\/wp\/v2\/comments?post=19994"}],"version-history":[{"count":2,"href":"https:\/\/portaldenoticias.net\/ffsantos\/wp-json\/wp\/v2\/posts\/19994\/revisions"}],"predecessor-version":[{"id":19999,"href":"https:\/\/portaldenoticias.net\/ffsantos\/wp-json\/wp\/v2\/posts\/19994\/revisions\/19999"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portaldenoticias.net\/ffsantos\/wp-json\/wp\/v2\/media\/19996"}],"wp:attachment":[{"href":"https:\/\/portaldenoticias.net\/ffsantos\/wp-json\/wp\/v2\/media?parent=19994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaldenoticias.net\/ffsantos\/wp-json\/wp\/v2\/categories?post=19994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaldenoticias.net\/ffsantos\/wp-json\/wp\/v2\/tags?post=19994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}