{"id":19586,"date":"2024-12-01T21:23:43","date_gmt":"2024-12-02T00:23:43","guid":{"rendered":"https:\/\/www.portaldenoticias.net\/ffsantos\/?p=19586"},"modified":"2024-12-01T21:23:43","modified_gmt":"2024-12-02T00:23:43","slug":"vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular","status":"publish","type":"post","link":"https:\/\/portaldenoticias.net\/ffsantos\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\/","title":{"rendered":"VAI PEDIR COMIDA OU CONSULTAR SALDO? NA NOVA ERA DA \u201cIA\u201d, APENAS D\u00ca UMA ORDEM AO CELULAR"},"content":{"rendered":"<p style=\"text-align: center\"><strong><em><a href=\"https:\/\/www.portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2024\/12\/Foto-1-Imagem2.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-19588\" src=\"https:\/\/www.portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2024\/12\/Foto-1-Imagem2.png\" alt=\"\" width=\"888\" height=\"592\" srcset=\"https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2024\/12\/Foto-1-Imagem2.png 888w, https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2024\/12\/Foto-1-Imagem2-300x200.png 300w, https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2024\/12\/Foto-1-Imagem2-768x512.png 768w, https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2024\/12\/Foto-1-Imagem2-150x100.png 150w, https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2024\/12\/Foto-1-Imagem2-450x300.png 450w\" sizes=\"auto, (max-width: 888px) 100vw, 888px\" \/><\/a>As arquitetas Carolina Montalvao e Luiza Sena utilizam ferramentas de intelig\u00eancia artificial no desenvolvimento de seus projetos &#8211; Tarefas cotidianas ser\u00e3o feitas sem abrir aplicativos. Smartphones que chegam a partir de 2025 ter\u00e3o habilidade de interagir com usu\u00e1rios &#8211; Foto: Leo Martins<\/em><\/strong><\/p>\n<p>Primeiro, a intelig\u00eancia artificial (IA) generativa permitiu criar resumos de texto, gerar imagens e traduzir conversas em tempo real durante videoconfer\u00eancias. Em seguida, ganharam espa\u00e7o aplica\u00e7\u00f5es mais complexas, que podem atender clientes, gerenciar fluxos de produ\u00e7\u00e3o ou ajudar a desenvolver produtos numa empresa.<\/p>\n<p>\u00c9 assim que, desde o lan\u00e7amento do ChatGPT, h\u00e1 dois anos, que a IA generativa tem transformado a rela\u00e7\u00e3o dos usu\u00e1rios com seus celulares e computadores. Agora, as gigantes globais da tecnologia prometem tornar essa tecnologia ainda mais integrada ao cotidiano.<\/p>\n<p>J\u00e1 em 2025, novos aparelhos dotados de superchips e ferramentas de IA para <strong><em>\u201cconversar\u201d<\/em><\/strong> com seus usu\u00e1rios chegam para abrir uma nova fase de desenvolvimento dessa tecnologia.<\/p>\n<p>Na chamada IA multimodal, o usu\u00e1rio vai <strong><em>\u201cfalar\u201d<\/em><\/strong> com o dispositivo sem a necessidade de abrir um aplicativo. Ser\u00e1 poss\u00edvel, por exemplo, solicitar ao celular o saldo na conta banc\u00e1ria, marcar as f\u00e9rias ou encomendar o jantar sem ter de interagir com o app de banco, hospedagem ou delivery. Bastar\u00e1 um comando de voz e a IA percorrer\u00e1 sozinha os caminhos para cumprir a tarefa.<\/p>\n<p>Na pr\u00e1tica, segundo especialistas e empresas, a promessa \u00e9 que a IA <strong><em>\u201centenda o contexto\u201d<\/em><\/strong> usando todas as fontes de dados nos aparelhos, como informa\u00e7\u00f5es capturadas em c\u00e2meras, GPS, microfones, carteiras digitais e apps j\u00e1 instalados para gerar respostas com baixo \u00edndice de erros.<\/p>\n<p>Jesper Rhode, fundador da consultoria de tecnologia Tr4nsform, compara esse deslocamento da IA do software para o hardware a uma f\u00e1brica:<\/p>\n<p>&#8211; H\u00e1 dois anos, eram apenas pequenos blocos isolados em uma linha de montagem. Agora, essas unidades est\u00e3o se conectando e formando uma linha de produ\u00e7\u00e3o automatizada, permitindo que usu\u00e1rios e aparelhos tenham uma conversa natural, que vai sendo aperfei\u00e7oada conforme o uso e o hist\u00f3rico das prefer\u00eancias. E a intelig\u00eancia artificial \u00e9 o combust\u00edvel. Voc\u00ea vai conversar com o celular e o computador e pedir o que quiser.<\/p>\n<p>E a corrida entre as big techs est\u00e1 acelerada. A Apple, por exemplo, que anunciou recentemente o Apple Intelligence, sua plataforma de IA, iniciar\u00e1 neste m\u00eas a integra\u00e7\u00e3o da Siri e das ferramentas de escrita do iPhone com o ChatGPT, permitindo que sua assistente virtual busque informa\u00e7\u00f5es em e-mails e calend\u00e1rio, por exemplo.<\/p>\n<p>Dispon\u00edvel em ingl\u00eas inicialmente, a americana diz que a novidade ter\u00e1 outros idiomas, como o portugu\u00eas, ao longo do pr\u00f3ximo ano.<\/p>\n<p style=\"text-align: center\"><strong><em>Info nas c\u00e2meras<\/em><\/strong><\/p>\n<figure id=\"attachment_19587\" aria-describedby=\"caption-attachment-19587\" style=\"width: 648px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2024\/12\/Foto-2-Imagem1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-19587\" src=\"https:\/\/www.portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2024\/12\/Foto-2-Imagem1.png\" alt=\"Celular tem novo sistema de c\u00e2meras, telas maiores e recursos de intelig\u00eancia artificial\" width=\"648\" height=\"248\" srcset=\"https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2024\/12\/Foto-2-Imagem1.png 648w, https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2024\/12\/Foto-2-Imagem1-300x115.png 300w, https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2024\/12\/Foto-2-Imagem1-150x57.png 150w, https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2024\/12\/Foto-2-Imagem1-450x172.png 450w\" sizes=\"auto, (max-width: 648px) 100vw, 648px\" \/><\/a><figcaption id=\"caption-attachment-19587\" class=\"wp-caption-text\">Celular tem novo sistema de c\u00e2meras, telas maiores e recursos de intelig\u00eancia artificial<\/figcaption><\/figure>\n<p>Fabricantes de smartphones como Samsung, Xiaomi, Realme e Asus j\u00e1 deram pistas da pr\u00f3xima gera\u00e7\u00e3o de dispositivos com IA ap\u00f3s anunciarem parceria com a Qualcomm, que apresentou recentemente seu novo processador preparado para os desafios da nova tecnologia, o Snapdragon 8 Elite.<\/p>\n<p>A nova IA na palma da m\u00e3o vai permitir fun\u00e7\u00f5es at\u00e9 agora restritas a filmes de fic\u00e7\u00e3o cient\u00edfica, como perguntar ao celular o significado de algo captado pela c\u00e2mera em tempo real. Ser\u00e1 poss\u00edvel, por exemplo, fotografar a conta de um restaurante e dividi-la proporcionalmente entre as pessoas \u00e0 mesa.<\/p>\n<p>&#8211; A IA generativa passa a ser personalizada e multimodal diretamente no dispositivo, permitindo a compreens\u00e3o da fala, do contexto e das imagens para aprimorar tarefas de trabalho e lazer. Ap\u00f3s o celular se tornar o novo computador, os aparelhos podem agora entender como os seres humanos se comunicam e a sua linguagem &#8211; diz Chris Patrick, vice-presidente s\u00eanior e gerente-geral de Aparelhos M\u00f3veis da Qualcomm. &#8211; A IA permitir\u00e1 aos dispositivos entender o ambiente ao redor, reconhecendo sons e espa\u00e7os com precis\u00e3o.<\/p>\n<p>A Samsung deve anunciar em janeiro o S25 em parceria com Qualcomm e Google. Ao longo deste ano, a sul-coreana lan\u00e7ou o Galaxy AI, que ajudou a popularizar recursos generativos, como edi\u00e7\u00e3o e cria\u00e7\u00e3o de imagens, tradu\u00e7\u00e3o de liga\u00e7\u00f5es e resumo de textos.<\/p>\n<p>&#8211; A IA est\u00e1 mudando a forma como as pessoas se comunicam e se relacionam. E isso n\u00e3o apenas no celular, mas tamb\u00e9m em PCs e rel\u00f3gios com IA, tanto no pr\u00f3prio aparelho como na nuvem. Com essas solu\u00e7\u00f5es, come\u00e7aremos a ver os benef\u00edcios da IA &#8211; afirma TM Roh, chefe global da Divis\u00e3o de Dispositivos M\u00f3veis da Samsung.<\/p>\n<p style=\"text-align: center\"><strong><em>Intelig\u00eancia artificial: ferramenta recria personagens ic\u00f4nicos com tra\u00e7os &#8216;realistas&#8217;; veja imagens:<\/em><\/strong><\/p>\n<p style=\"text-align: center\"><strong><em>(<a href=\"https:\/\/oglobo.globo.com\/economia\/tecnologia\/noticia\/2024\/12\/01\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular.ghtml?utm_source=newsdegustacao&amp;utm_medium=email&amp;utm_campaign=newsviuisso\">https:\/\/oglobo.globo.com\/economia\/tecnologia\/noticia\/2024\/12\/01\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular.ghtml?utm_source=newsdegustacao&amp;utm_medium=email&amp;utm_campaign=newsviuisso<\/a>)<\/em><\/strong><\/p>\n<p style=\"text-align: left\">As chinesas Xiaomi e a Realme j\u00e1 anunciaram no exterior de seus novos telefones com IA multimodal, o Xiaomi 15 e o Realme GT 7 Pro, respectivamente. A nova gera\u00e7\u00e3o contar\u00e1 ainda com o 5G Advanced, que amplia a velocidade de conex\u00e3o j\u00e1 alta do 5G atual.<\/p>\n<p>Al\u00e9m dos smartphones, os fabricantes investem em notebooks integrando IA na unidade central de processamento (CPU) e no mecanismo gr\u00e1fico (GPU) para proporcionar respostas mais r\u00e1pidas e precisas. Alguns j\u00e1 s\u00e3o fabricados com teclas que acionam a IA diretamente.<\/p>\n<p>A Dell, por exemplo, apresentou recentemente o notebook Latitude 5455 com os novos recursos do Copilot+, da Microsoft. A m\u00e1quina atinge at\u00e9 45 trilh\u00f5es de opera\u00e7\u00f5es por segundo e sua bateria dura at\u00e9 27 horas.<\/p>\n<p>Rodrigo Nogueira, fundador da Maritaca IA e doutor em Ci\u00eancia da Computa\u00e7\u00e3o pela New York University (NYU), explica que as novidades s\u00f3 s\u00e3o poss\u00edveis gra\u00e7as \u00e0 evolu\u00e7\u00e3o do hardware, com aparelhos mais potentes e baterias de maior dura\u00e7\u00e3o:<\/p>\n<p>&#8211; Com mais capacidade, os aparelhos processam v\u00eddeos, fotos e fala de forma mais r\u00e1pida. Isso vai permitir uma intera\u00e7\u00e3o mais complexa com os aparelhos por voz, deixando a era do clique atr\u00e1s de clique para tr\u00e1s. Esse movimento tende a ser cada vez mais r\u00e1pido.<\/p>\n<p style=\"text-align: center\"><strong><em>Dia a dia digitalizado<\/em><\/strong><\/p>\n<p>Muita gente j\u00e1 incorporou a IA generativa ao cotidiano e est\u00e1 pronta para come\u00e7ar a dialogar com seus aparelhos, uma vez que a principal interface da nova tecnologia \u00e9 a linguagem. As arquitetas Luiza Sena e Carolina Montalv\u00e3o consideram o celular e o tablet uma <strong><em>\u201cextens\u00e3o\u201d<\/em><\/strong> de suas pranchetas. Aderiram a aplicativos de IA que ajudam desde o esbo\u00e7o inicial at\u00e9 a apresenta\u00e7\u00e3o final de um projeto ao cliente.<\/p>\n<p>&#8211; Com um aplicativo, apontamos a c\u00e2mera do celular para medir espa\u00e7os e criar plantas diretamente, otimizando nosso tempo e diminuindo a necessidade de medi\u00e7\u00f5es manuais. Com \u00f3culos de realidade virtual, os clientes conseguem, na pr\u00f3pria obra, visualizar como tudo vai ficar. Permitem enxergar o projeto em escala real e caminhar virtualmente pelo espa\u00e7o antes mesmo de a obra come\u00e7ar. A IA n\u00e3o substitui nossa vis\u00e3o como arquitetas, mas potencializa nosso trabalho &#8211; diz Luiza.<\/p>\n<p style=\"text-align: center\"><strong><em>Entenda: Alexa, Google e Siri escutam as nossas conversas?<\/em><\/strong><\/p>\n<p style=\"text-align: center\">( <a href=\"https:\/\/oglobo.globo.com\/economia\/tecnologia\/noticia\/2024\/03\/31\/alexa-google-e-siri-escutam-as-nossas-conversas-entenda.ghtml\">https:\/\/oglobo.globo.com\/economia\/tecnologia\/noticia\/2024\/03\/31\/alexa-google-e-siri-escutam-as-nossas-conversas-entenda.ghtml<\/a>)<\/p>\n<figure id=\"attachment_19589\" aria-describedby=\"caption-attachment-19589\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2024\/12\/Foto-3-Imagem4.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-19589\" src=\"https:\/\/www.portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2024\/12\/Foto-3-Imagem4.png\" alt=\"\" width=\"1000\" height=\"666\" srcset=\"https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2024\/12\/Foto-3-Imagem4.png 1000w, https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2024\/12\/Foto-3-Imagem4-300x200.png 300w, https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2024\/12\/Foto-3-Imagem4-768x511.png 768w, https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2024\/12\/Foto-3-Imagem4-150x100.png 150w, https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2024\/12\/Foto-3-Imagem4-450x300.png 450w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><figcaption id=\"caption-attachment-19589\" class=\"wp-caption-text\">Fernando Brand\u00e3o, fundador da sorveteria Sol e Neve, e Marcos Monteiro, diretor de Marketing da empresa, co-criaram um sorvete com IA &#8211; Foto: Domingos Peixoto<\/figcaption><\/figure>\n<p>Foi essa mesma l\u00f3gica que levou Fernando Brand\u00e3o, fundador da sorveteria Sole Neve, a criar um sorvete com IA. Ele conta que combinou a vis\u00e3o estrat\u00e9gica da marca com algoritmos que analisam prefer\u00eancias de mercado, combina\u00e7\u00f5es inusitadas e tend\u00eancias de consumo. Assim, nasceu uma vers\u00e3o com cacau, castanha de caju caramelizada e rapadura, finalizada com geleia de pimenta dedo de mo\u00e7a.<\/p>\n<p>&#8211; Deu certo. O novo produto ganhou a aprova\u00e7\u00e3o do p\u00fablico e foi para o card\u00e1pio das 200 lojas. J\u00e1 usamos a IA para auxiliar no gerenciamento da empresa, utilizando assistentes para organizar compras, gerenciar fornecedores e otimizar processos internos \u2014afirma Brand\u00e3o, que trouxe o novo sabor para Copacabana, na Zona Sul do Rio, onde abriu a primeira loja carioca da rede.<\/p>\n<p>As inova\u00e7\u00f5es dos dispositivos com IA v\u00eam acompanhadas ainda de aprimoramentos nos sistemas de \u00e1udio e imagem. Os novos smartphones ter\u00e3o capacidade de converter qualquer imagem em 4K. A c\u00e2mera ter\u00e1 capacidade de adicionar mais luz apenas em pontos espec\u00edficos da foto e do v\u00eddeo, como no rosto da pessoa enquadrada com a ajuda de algoritmos que mapeiam as imagens e d\u00e3o respostas imediatas.<\/p>\n<p>O zoom com qualidade est\u00e1 cada vez mais potente, chegando a 20 vezes. O GPS, por sua vez, ganha mais precis\u00e3o e poder\u00e1 antecipar os pr\u00f3ximos movimentos dos usu\u00e1rios, aprimorando a conectividade.<\/p>\n<p>Combinando todas essas novas fun\u00e7\u00f5es, a Asus lan\u00e7a o Rog Phone 9, voltado para o p\u00fablico gamer. A IA multimodal vai permitir que as imagens dos jogos se apresentem bem realistas, reproduzidas em 3D. Um dos diferenciais, diz Sascha Krohn, diretor de Marketing da Asus, \u00e9 que os smartphones ter\u00e3o pela primeira vez uma CPU semelhante \u00e0 de notebooks.<\/p>\n<p>&#8211; Essas inova\u00e7\u00f5es ganhar\u00e3o tra\u00e7\u00e3o em 2025. A ado\u00e7\u00e3o ser\u00e1 r\u00e1pida. Por outro lado, a IA \u00e9 constantemente treinada e atualizada para melhorar a precis\u00e3o das respostas em um cen\u00e1rio cercado de desafios. H\u00e1 a necessidade de as big techs informarem como esses ecossistemas de IA s\u00e3o constru\u00eddos. \u00c9 importante que o usu\u00e1rio entenda at\u00e9 que ponto ele pode fornecer informa\u00e7\u00f5es pessoais a essas plataformas &#8211; alerta Jesper Rhode, da consultoria de tecnologia Tr4nsform.<\/p>\n<p><strong><em>Fonte:<\/em><\/strong> <a href=\"https:\/\/oglobo.globo.com\">https:\/\/oglobo.globo.com<\/a> &#8211; Por Bruno Rosa &#8211; Rio de Janeiro<\/p>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n<p style=\"text-align: center\"><strong><em>Blog do Florisvaldo &#8211; Informa\u00e7\u00e3o Com Imparcialidade<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>As arquitetas Carolina Montalvao e Luiza Sena utilizam ferramentas de intelig\u00eancia artificial no desenvolvimento de seus projetos &#8211; Tarefas cotidianas ser\u00e3o feitas sem abrir aplicativos. Smartphones que chegam a partir de 2025 ter\u00e3o habilidade de interagir com usu\u00e1rios &#8211; Foto: Leo Martins Primeiro, a intelig\u00eancia artificial (IA) generativa permitiu criar resumos de texto, gerar imagens<\/p>\n","protected":false},"author":2,"featured_media":19588,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,1,6],"tags":[],"class_list":{"0":"post-19586","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-destaques","9":"category-economia"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VAI PEDIR COMIDA OU CONSULTAR SALDO? NA NOVA ERA DA \u201cIA\u201d, APENAS D\u00ca UMA ORDEM AO CELULAR - Blog do Florisvaldo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/portaldenoticias.net\/ffsantos\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VAI PEDIR COMIDA OU CONSULTAR SALDO? NA NOVA ERA DA \u201cIA\u201d, APENAS D\u00ca UMA ORDEM AO CELULAR - Blog do Florisvaldo\" \/>\n<meta property=\"og:description\" content=\"As arquitetas Carolina Montalvao e Luiza Sena utilizam ferramentas de intelig\u00eancia artificial no desenvolvimento de seus projetos &#8211; Tarefas cotidianas ser\u00e3o feitas sem abrir aplicativos. Smartphones que chegam a partir de 2025 ter\u00e3o habilidade de interagir com usu\u00e1rios &#8211; Foto: Leo Martins Primeiro, a intelig\u00eancia artificial (IA) generativa permitiu criar resumos de texto, gerar imagens\" \/>\n<meta property=\"og:url\" content=\"https:\/\/portaldenoticias.net\/ffsantos\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Florisvaldo\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-02T00:23:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2024\/12\/Foto-1-Imagem2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"888\" \/>\n\t<meta property=\"og:image:height\" content=\"592\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Florisvaldo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Florisvaldo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\\\/\"},\"author\":{\"name\":\"Florisvaldo\",\"@id\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/#\\\/schema\\\/person\\\/709c788ecb22f2378d698c2cd46cecc3\"},\"headline\":\"VAI PEDIR COMIDA OU CONSULTAR SALDO? NA NOVA ERA DA \u201cIA\u201d, APENAS D\u00ca UMA ORDEM AO CELULAR\",\"datePublished\":\"2024-12-02T00:23:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\\\/\"},\"wordCount\":1676,\"commentCount\":3,\"image\":{\"@id\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Foto-1-Imagem2.png\",\"articleSection\":[\"Brasil\",\"Destaques\",\"Economia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\\\/\",\"url\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\\\/\",\"name\":\"VAI PEDIR COMIDA OU CONSULTAR SALDO? NA NOVA ERA DA \u201cIA\u201d, APENAS D\u00ca UMA ORDEM AO CELULAR - Blog do Florisvaldo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Foto-1-Imagem2.png\",\"datePublished\":\"2024-12-02T00:23:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/#\\\/schema\\\/person\\\/709c788ecb22f2378d698c2cd46cecc3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\\\/#primaryimage\",\"url\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Foto-1-Imagem2.png\",\"contentUrl\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Foto-1-Imagem2.png\",\"width\":888,\"height\":592},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VAI PEDIR COMIDA OU CONSULTAR SALDO? NA NOVA ERA DA \u201cIA\u201d, APENAS D\u00ca UMA ORDEM AO CELULAR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/#website\",\"url\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/\",\"name\":\"Blog do Florisvaldo |\",\"description\":\"Informa\u00e7\u00e3o com imparcialidade\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/#\\\/schema\\\/person\\\/709c788ecb22f2378d698c2cd46cecc3\",\"name\":\"Florisvaldo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23c59839b4c874bb227d4916d18ba065e405a73d0e423fa9255ba9436604e628?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23c59839b4c874bb227d4916d18ba065e405a73d0e423fa9255ba9436604e628?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23c59839b4c874bb227d4916d18ba065e405a73d0e423fa9255ba9436604e628?s=96&d=mm&r=g\",\"caption\":\"Florisvaldo\"},\"url\":\"https:\\\/\\\/portaldenoticias.net\\\/ffsantos\\\/author\\\/ffsantos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VAI PEDIR COMIDA OU CONSULTAR SALDO? NA NOVA ERA DA \u201cIA\u201d, APENAS D\u00ca UMA ORDEM AO CELULAR - Blog do Florisvaldo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/portaldenoticias.net\/ffsantos\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\/","og_locale":"pt_BR","og_type":"article","og_title":"VAI PEDIR COMIDA OU CONSULTAR SALDO? NA NOVA ERA DA \u201cIA\u201d, APENAS D\u00ca UMA ORDEM AO CELULAR - Blog do Florisvaldo","og_description":"As arquitetas Carolina Montalvao e Luiza Sena utilizam ferramentas de intelig\u00eancia artificial no desenvolvimento de seus projetos &#8211; Tarefas cotidianas ser\u00e3o feitas sem abrir aplicativos. Smartphones que chegam a partir de 2025 ter\u00e3o habilidade de interagir com usu\u00e1rios &#8211; Foto: Leo Martins Primeiro, a intelig\u00eancia artificial (IA) generativa permitiu criar resumos de texto, gerar imagens","og_url":"https:\/\/portaldenoticias.net\/ffsantos\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\/","og_site_name":"Blog do Florisvaldo","article_published_time":"2024-12-02T00:23:43+00:00","og_image":[{"width":888,"height":592,"url":"https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2024\/12\/Foto-1-Imagem2.png","type":"image\/png"}],"author":"Florisvaldo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Florisvaldo","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/portaldenoticias.net\/ffsantos\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\/#article","isPartOf":{"@id":"https:\/\/portaldenoticias.net\/ffsantos\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\/"},"author":{"name":"Florisvaldo","@id":"https:\/\/portaldenoticias.net\/ffsantos\/#\/schema\/person\/709c788ecb22f2378d698c2cd46cecc3"},"headline":"VAI PEDIR COMIDA OU CONSULTAR SALDO? NA NOVA ERA DA \u201cIA\u201d, APENAS D\u00ca UMA ORDEM AO CELULAR","datePublished":"2024-12-02T00:23:43+00:00","mainEntityOfPage":{"@id":"https:\/\/portaldenoticias.net\/ffsantos\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\/"},"wordCount":1676,"commentCount":3,"image":{"@id":"https:\/\/portaldenoticias.net\/ffsantos\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\/#primaryimage"},"thumbnailUrl":"https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2024\/12\/Foto-1-Imagem2.png","articleSection":["Brasil","Destaques","Economia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/portaldenoticias.net\/ffsantos\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/portaldenoticias.net\/ffsantos\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\/","url":"https:\/\/portaldenoticias.net\/ffsantos\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\/","name":"VAI PEDIR COMIDA OU CONSULTAR SALDO? NA NOVA ERA DA \u201cIA\u201d, APENAS D\u00ca UMA ORDEM AO CELULAR - Blog do Florisvaldo","isPartOf":{"@id":"https:\/\/portaldenoticias.net\/ffsantos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/portaldenoticias.net\/ffsantos\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\/#primaryimage"},"image":{"@id":"https:\/\/portaldenoticias.net\/ffsantos\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\/#primaryimage"},"thumbnailUrl":"https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2024\/12\/Foto-1-Imagem2.png","datePublished":"2024-12-02T00:23:43+00:00","author":{"@id":"https:\/\/portaldenoticias.net\/ffsantos\/#\/schema\/person\/709c788ecb22f2378d698c2cd46cecc3"},"breadcrumb":{"@id":"https:\/\/portaldenoticias.net\/ffsantos\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/portaldenoticias.net\/ffsantos\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/portaldenoticias.net\/ffsantos\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\/#primaryimage","url":"https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2024\/12\/Foto-1-Imagem2.png","contentUrl":"https:\/\/portaldenoticias.net\/ffsantos\/wp-content\/uploads\/2024\/12\/Foto-1-Imagem2.png","width":888,"height":592},{"@type":"BreadcrumbList","@id":"https:\/\/portaldenoticias.net\/ffsantos\/vai-pedir-comida-ou-consultar-saldo-na-nova-era-da-ia-apenas-de-uma-ordem-ao-celular\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/portaldenoticias.net\/ffsantos\/"},{"@type":"ListItem","position":2,"name":"VAI PEDIR COMIDA OU CONSULTAR SALDO? NA NOVA ERA DA \u201cIA\u201d, APENAS D\u00ca UMA ORDEM AO CELULAR"}]},{"@type":"WebSite","@id":"https:\/\/portaldenoticias.net\/ffsantos\/#website","url":"https:\/\/portaldenoticias.net\/ffsantos\/","name":"Blog do Florisvaldo |","description":"Informa\u00e7\u00e3o com imparcialidade","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/portaldenoticias.net\/ffsantos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/portaldenoticias.net\/ffsantos\/#\/schema\/person\/709c788ecb22f2378d698c2cd46cecc3","name":"Florisvaldo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/23c59839b4c874bb227d4916d18ba065e405a73d0e423fa9255ba9436604e628?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/23c59839b4c874bb227d4916d18ba065e405a73d0e423fa9255ba9436604e628?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/23c59839b4c874bb227d4916d18ba065e405a73d0e423fa9255ba9436604e628?s=96&d=mm&r=g","caption":"Florisvaldo"},"url":"https:\/\/portaldenoticias.net\/ffsantos\/author\/ffsantos\/"}]}},"_links":{"self":[{"href":"https:\/\/portaldenoticias.net\/ffsantos\/wp-json\/wp\/v2\/posts\/19586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portaldenoticias.net\/ffsantos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaldenoticias.net\/ffsantos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaldenoticias.net\/ffsantos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaldenoticias.net\/ffsantos\/wp-json\/wp\/v2\/comments?post=19586"}],"version-history":[{"count":1,"href":"https:\/\/portaldenoticias.net\/ffsantos\/wp-json\/wp\/v2\/posts\/19586\/revisions"}],"predecessor-version":[{"id":19590,"href":"https:\/\/portaldenoticias.net\/ffsantos\/wp-json\/wp\/v2\/posts\/19586\/revisions\/19590"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portaldenoticias.net\/ffsantos\/wp-json\/wp\/v2\/media\/19588"}],"wp:attachment":[{"href":"https:\/\/portaldenoticias.net\/ffsantos\/wp-json\/wp\/v2\/media?parent=19586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaldenoticias.net\/ffsantos\/wp-json\/wp\/v2\/categories?post=19586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaldenoticias.net\/ffsantos\/wp-json\/wp\/v2\/tags?post=19586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}